{"id":10568,"date":"2023-12-12T13:11:36","date_gmt":"2023-12-12T13:11:36","guid":{"rendered":"https:\/\/osesa.cl\/index.php\/las-claves-para-detectar-y-combatir-los-incendios-industriales-en-forma-eficiente-copy\/"},"modified":"2024-12-05T18:18:27","modified_gmt":"2024-12-05T18:18:27","slug":"estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023","status":"publish","type":"post","link":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/","title":{"rendered":"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023."},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1452687555475{margin-bottom: 100px !important;}&#8221;][vc_column offset=&#8221;vc_col-lg-9 vc_col-md-9&#8243; css=&#8221;.vc_custom_1452702342137{padding-right: 45px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;no_stripe&#8221;][stm_post_details][vc_column_text css=&#8221;.vc_custom_1702386743570{margin-bottom: 20px !important;}&#8221;]Estamos felices de haber participado junto a ABLOY en el encuentro de jefes de seguridad empresarial ESEM 2023. En una jornada inigualable, exhibimos las innovadoras soluciones de seguridad que caracterizan a ABLOY.<\/p>\n<p>Desde los sistemas de acceso avanzados BEAT, hasta CLIQ, para poder presentar las caracter\u00edsticas de ciberseguridad con las que estos productos est\u00e1n protegidos. Adem\u00e1s, presentamos nuestras cerraduras de alta resistencia, captando la atenci\u00f3n de profesionales y expertos en seguridad.<\/p>\n<p>Agradecemos tambi\u00e9n a nuestro equipo, quienes ayudaron a que nuestra participaci\u00f3n reforzara la confianza en ABLOY Latinoam\u00e9rica y OSESA, quienes seguimos trabajando para elevar los est\u00e1ndares de seguridad en cada paso que damos.[\/vc_column_text][vc_raw_html]JTNDc3R5bGUlM0UucGFnZV90aXRsZSUyMCU3QiUwQSUyMCUyMCUyMCUyMGRpc3BsYXklM0ElMjBub25lJTIwJTIxaW1wb3J0YW50JTNCJTBBJTdEJTNDJTJGc3R5bGUlM0U=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/4&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][stm_sidebar sidebar=&#8221;527&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;third_bg_color&#8221; css=&#8221;.vc_custom_1688415194796{margin-bottom: -60px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_cta h2=&#8221;Solicita tu presupuesto&#8221; h2_font_container=&#8221;tag:h2|font_size:25px|text_align:center|color:%23000000&#8243; h2_use_theme_fonts=&#8221;yes&#8221; shape=&#8221;square&#8221; style=&#8221;flat&#8221; add_button=&#8221;right&#8221; btn_title=&#8221;aqu\u00ed&#8221; btn_style=&#8221;flat&#8221; btn_color=&#8221;theme_style_2&#8243; btn_align=&#8221;left&#8221; use_custom_fonts_h2=&#8221;true&#8221; btn_button_block=&#8221;true&#8221; el_class=&#8221;third_bg_color&#8221; css=&#8221;.vc_custom_1695315286471{margin-bottom: 0px !important;}&#8221; btn_link=&#8221;url:https%3A%2F%2Fosesa.cl%2Findex.php%2Fcontacto%2F|title:Contacto&#8221;][\/vc_cta][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Estamos felices de haber participado junto a ABLOY en el encuentro de jefes de seguridad empresarial ESEM 2023. En una jornada inigualable<\/p>\n","protected":false},"author":3,"featured_media":10573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[20],"tags":[159],"class_list":["post-10568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023. - Osesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023. - Osesa\" \/>\n<meta property=\"og:description\" content=\"Estamos felices de haber participado junto a ABLOY en el encuentro de jefes de seguridad empresarial ESEM 2023. En una jornada inigualable\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Osesa\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-12T13:11:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T18:18:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Osesa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Osesa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/\",\"url\":\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/\",\"name\":\"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023. - Osesa\",\"isPartOf\":{\"@id\":\"https:\/\/osesa.cl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg\",\"datePublished\":\"2023-12-12T13:11:36+00:00\",\"dateModified\":\"2024-12-05T18:18:27+00:00\",\"author\":{\"@id\":\"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98\"},\"breadcrumb\":{\"@id\":\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#primaryimage\",\"url\":\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg\",\"contentUrl\":\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/osesa.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/osesa.cl\/#website\",\"url\":\"https:\/\/osesa.cl\/\",\"name\":\"Osesa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/osesa.cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98\",\"name\":\"Osesa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/osesa.cl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g\",\"caption\":\"Osesa\"},\"url\":\"https:\/\/osesa.cl\/index.php\/author\/admin-osesa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023. - Osesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023. - Osesa","og_description":"Estamos felices de haber participado junto a ABLOY en el encuentro de jefes de seguridad empresarial ESEM 2023. En una jornada inigualable","og_url":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/","og_site_name":"Osesa","article_published_time":"2023-12-12T13:11:36+00:00","article_modified_time":"2024-12-05T18:18:27+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg","type":"image\/jpeg"}],"author":"Osesa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Osesa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/","url":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/","name":"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023. - Osesa","isPartOf":{"@id":"https:\/\/osesa.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#primaryimage"},"image":{"@id":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg","datePublished":"2023-12-12T13:11:36+00:00","dateModified":"2024-12-05T18:18:27+00:00","author":{"@id":"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98"},"breadcrumb":{"@id":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#primaryimage","url":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg","contentUrl":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/12\/Not_abloy_2_-2-1.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/osesa.cl\/index.php\/estuvimos-presentes-en-el-encuentro-de-jefes-de-seguridad-empresarial-esem-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osesa.cl\/"},{"@type":"ListItem","position":2,"name":"Estuvimos presentes en el encuentro de jefes de seguridad empresarial, ESEM 2023."}]},{"@type":"WebSite","@id":"https:\/\/osesa.cl\/#website","url":"https:\/\/osesa.cl\/","name":"Osesa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osesa.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98","name":"Osesa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osesa.cl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g","caption":"Osesa"},"url":"https:\/\/osesa.cl\/index.php\/author\/admin-osesa\/"}]}},"_links":{"self":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts\/10568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/comments?post=10568"}],"version-history":[{"count":2,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts\/10568\/revisions"}],"predecessor-version":[{"id":12579,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts\/10568\/revisions\/12579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/media\/10573"}],"wp:attachment":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/media?parent=10568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/categories?post=10568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/tags?post=10568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}