{"id":9727,"date":"2023-08-09T15:40:52","date_gmt":"2023-08-09T15:40:52","guid":{"rendered":"http:\/\/andesrank.cl\/?p=9727"},"modified":"2024-12-05T18:19:33","modified_gmt":"2024-12-05T18:19:33","slug":"osesa-mantiene-su-certificacion-iso-9001","status":"publish","type":"post","link":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/","title":{"rendered":"OSESA mantiene su certificaci\u00f3n ISO 9001"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1452687555475{margin-bottom: 100px !important;}&#8221;][vc_column offset=&#8221;vc_col-lg-9 vc_col-md-9&#8243; css=&#8221;.vc_custom_1452702342137{padding-right: 45px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;no_stripe&#8221;][stm_post_details][vc_column_text css=&#8221;.vc_custom_1691595698214{margin-bottom: 20px !important;}&#8221;]Nos enorgullece contar con una de las principales certificaciones requeridas por empresas mineras, generadoras de energ\u00eda y de infraestructura cr\u00edtica: la ISO 9001 en Gesti\u00f3n de la Calidad. Esta certificaci\u00f3n internacional nos fue entregada por Applus+ el a\u00f1o 2021 y mantenida el 2022 y 2023. Es un claro respaldando nuestros altos est\u00e1ndares de calidad y mejora continua. Como equipo OSESA tenemos el desaf\u00edo de obtener la Re-Certificaci\u00f3n a comienzos del 2024.<\/p>\n<p>Gracias a esta certificaci\u00f3n, podemos mirar nuestros procesos con foco en la mejora continua y trabajar de manera eficiente, segura y \u00e1gil en los proyectos desafiantes de nuestros clientes. Nuestro compromiso con la excelencia se fortalece a\u00fan m\u00e1s al ofrecer un servicio a la medida y conocedor de las problem\u00e1ticas de cada industria.<\/p>\n<p>Adem\u00e1s, contamos con certificaciones de nuestros socios estrat\u00e9gicos ABLOY y Johnson Controls International, quienes ponen su nombre, experiencia y red de apoyo sobre los servicios entregados por OSESA. Nuestros colaboradores se encuentran fuertemente capacitados y poseen experiencia en la instalaci\u00f3n y mantenci\u00f3n de las soluciones de nuestros partners.[\/vc_column_text][vc_raw_html]JTNDc3R5bGUlM0UucGFnZV90aXRsZSUyMCU3QiUwQSUyMCUyMCUyMCUyMGRpc3BsYXklM0ElMjBub25lJTIwJTIxaW1wb3J0YW50JTNCJTBBJTdEJTNDJTJGc3R5bGUlM0U=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/4&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][stm_sidebar sidebar=&#8221;527&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;third_bg_color&#8221; css=&#8221;.vc_custom_1688415194796{margin-bottom: -60px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_cta h2=&#8221;Solicita tu presupuesto&#8221; h2_font_container=&#8221;tag:h2|font_size:25px|text_align:center|color:%23000000&#8243; h2_use_theme_fonts=&#8221;yes&#8221; shape=&#8221;square&#8221; style=&#8221;flat&#8221; add_button=&#8221;right&#8221; btn_title=&#8221;aqu\u00ed&#8221; btn_style=&#8221;flat&#8221; btn_color=&#8221;theme_style_2&#8243; btn_align=&#8221;left&#8221; use_custom_fonts_h2=&#8221;true&#8221; btn_button_block=&#8221;true&#8221; el_class=&#8221;third_bg_color&#8221; css=&#8221;.vc_custom_1695315286471{margin-bottom: 0px !important;}&#8221; btn_link=&#8221;url:https%3A%2F%2Fosesa.cl%2Findex.php%2Fcontacto%2F|title:Contacto&#8221;][\/vc_cta][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nos enorgullece contar con una de las principales certificaciones requeridas por empresas mineras, generadoras de energ\u00eda y de infraestructura cr\u00edtica: la ISO 9001 en Gesti\u00f3n de la Calidad.<\/p>\n","protected":false},"author":3,"featured_media":9867,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[20],"tags":[159],"class_list":["post-9727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OSESA mantiene su certificaci\u00f3n ISO 9001 - Osesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OSESA mantiene su certificaci\u00f3n ISO 9001 - Osesa\" \/>\n<meta property=\"og:description\" content=\"Nos enorgullece contar con una de las principales certificaciones requeridas por empresas mineras, generadoras de energ\u00eda y de infraestructura cr\u00edtica: la ISO 9001 en Gesti\u00f3n de la Calidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/\" \/>\n<meta property=\"og:site_name\" content=\"Osesa\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-09T15:40:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T18:19:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Osesa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Osesa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/\",\"url\":\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/\",\"name\":\"OSESA mantiene su certificaci\u00f3n ISO 9001 - Osesa\",\"isPartOf\":{\"@id\":\"https:\/\/osesa.cl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg\",\"datePublished\":\"2023-08-09T15:40:52+00:00\",\"dateModified\":\"2024-12-05T18:19:33+00:00\",\"author\":{\"@id\":\"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98\"},\"breadcrumb\":{\"@id\":\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#primaryimage\",\"url\":\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg\",\"contentUrl\":\"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/osesa.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OSESA mantiene su certificaci\u00f3n ISO 9001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/osesa.cl\/#website\",\"url\":\"https:\/\/osesa.cl\/\",\"name\":\"Osesa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/osesa.cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98\",\"name\":\"Osesa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/osesa.cl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g\",\"caption\":\"Osesa\"},\"url\":\"https:\/\/osesa.cl\/index.php\/author\/admin-osesa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OSESA mantiene su certificaci\u00f3n ISO 9001 - Osesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/","og_locale":"es_ES","og_type":"article","og_title":"OSESA mantiene su certificaci\u00f3n ISO 9001 - Osesa","og_description":"Nos enorgullece contar con una de las principales certificaciones requeridas por empresas mineras, generadoras de energ\u00eda y de infraestructura cr\u00edtica: la ISO 9001 en Gesti\u00f3n de la Calidad.","og_url":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/","og_site_name":"Osesa","article_published_time":"2023-08-09T15:40:52+00:00","article_modified_time":"2024-12-05T18:19:33+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg","type":"image\/jpeg"}],"author":"Osesa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Osesa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/","url":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/","name":"OSESA mantiene su certificaci\u00f3n ISO 9001 - Osesa","isPartOf":{"@id":"https:\/\/osesa.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#primaryimage"},"image":{"@id":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#primaryimage"},"thumbnailUrl":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg","datePublished":"2023-08-09T15:40:52+00:00","dateModified":"2024-12-05T18:19:33+00:00","author":{"@id":"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98"},"breadcrumb":{"@id":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#primaryimage","url":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg","contentUrl":"https:\/\/osesa.cl\/wp-content\/uploads\/2023\/08\/F_not_ose-2-1.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/osesa.cl\/index.php\/osesa-mantiene-su-certificacion-iso-9001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osesa.cl\/"},{"@type":"ListItem","position":2,"name":"OSESA mantiene su certificaci\u00f3n ISO 9001"}]},{"@type":"WebSite","@id":"https:\/\/osesa.cl\/#website","url":"https:\/\/osesa.cl\/","name":"Osesa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osesa.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osesa.cl\/#\/schema\/person\/4f76d4f9780be6126dc5bd3bd117ab98","name":"Osesa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osesa.cl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f381e27693fd7ebfa07b4e82119ef6975060e6ffbd9834391eca7807d0c9caa5?s=96&d=mm&r=g","caption":"Osesa"},"url":"https:\/\/osesa.cl\/index.php\/author\/admin-osesa\/"}]}},"_links":{"self":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts\/9727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/comments?post=9727"}],"version-history":[{"count":5,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts\/9727\/revisions"}],"predecessor-version":[{"id":12580,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/posts\/9727\/revisions\/12580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/media\/9867"}],"wp:attachment":[{"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/media?parent=9727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/categories?post=9727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osesa.cl\/index.php\/wp-json\/wp\/v2\/tags?post=9727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}